{"id":7349,"date":"2022-09-21T14:22:02","date_gmt":"2022-09-21T14:22:02","guid":{"rendered":"https:\/\/aquamarinespa.cz\/products\/whirlpools\/stainless-steel-whirlpools-imaginox\/"},"modified":"2022-11-28T11:25:29","modified_gmt":"2022-11-28T11:25:29","slug":"stainless-steel-whirlpools-imaginox","status":"publish","type":"page","link":"https:\/\/aquamarinespa.cz\/en\/products\/whirlpools\/stainless-steel-whirlpools-imaginox\/","title":{"rendered":"Stainless-steel whirlpools Imaginox"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":239,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"products-whirlpools-imaginox.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7349","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stainless steel hot tub Imaginox \u2248 Aquamarine Spa<\/title>\n<meta name=\"description\" content=\"Choose the size, water filtration system, location, depth of the bathtub, but also the availability of individual massage points and nozzles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aquamarinespa.cz\/en\/products\/whirlpools\/stainless-steel-whirlpools-imaginox\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stainless steel hot tub Imaginox \u2248 Aquamarine Spa\" \/>\n<meta property=\"og:description\" content=\"Choose the size, water filtration system, location, depth of the bathtub, but also the availability of individual massage points and nozzles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aquamarinespa.cz\/en\/products\/whirlpools\/stainless-steel-whirlpools-imaginox\/\" \/>\n<meta property=\"og:site_name\" content=\"Aquamarine Spa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aquamarinespacz\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-28T11:25:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aquamarinespa.cz\\\/en\\\/products\\\/whirlpools\\\/stainless-steel-whirlpools-imaginox\\\/\",\"url\":\"https:\\\/\\\/aquamarinespa.cz\\\/en\\\/products\\\/whirlpools\\\/stainless-steel-whirlpools-imaginox\\\/\",\"name\":\"Stainless steel hot tub Imaginox \u2248 Aquamarine Spa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aquamarinespa.cz\\\/en\\\/#website\"},\"datePublished\":\"2022-09-21T14:22:02+00:00\",\"dateModified\":\"2022-11-28T11:25:29+00:00\",\"description\":\"Choose the size, water filtration system, location, depth of the bathtub, but also the availability of individual massage points and nozzles.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aquamarinespa.cz\\\/en\\\/products\\\/whirlpools\\\/stainless-steel-whirlpools-imaginox\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aquamarinespa.cz\\\/en\\\/products\\\/whirlpools\\\/stainless-steel-whirlpools-imaginox\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aquamarinespa.cz\\\/en\\\/products\\\/whirlpools\\\/stainless-steel-whirlpools-imaginox\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aquamarinespa.cz\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/aquamarinespa.cz\\\/en\\\/produkty\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Whirlpools\",\"item\":\"https:\\\/\\\/aquamarinespa.cz\\\/en\\\/produkty\\\/virivky\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Stainless-steel whirlpools Imaginox\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aquamarinespa.cz\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/aquamarinespa.cz\\\/en\\\/\",\"name\":\"Aquamarine Spa\",\"description\":\"Experience the feeling of perfection\",\"publisher\":{\"@id\":\"https:\\\/\\\/aquamarinespa.cz\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aquamarinespa.cz\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aquamarinespa.cz\\\/en\\\/#organization\",\"name\":\"Aquamarine Spa\",\"url\":\"https:\\\/\\\/aquamarinespa.cz\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aquamarinespa.cz\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aquamarinespa.cz\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/aquamarinespa-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/aquamarinespa.cz\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/aquamarinespa-logo.jpg\",\"width\":1018,\"height\":499,\"caption\":\"Aquamarine Spa\"},\"image\":{\"@id\":\"https:\\\/\\\/aquamarinespa.cz\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aquamarinespacz\\\/\",\"https:\\\/\\\/www.instagram.com\\\/aquamarinespacz\\\/\",\"https:\\\/\\\/cz.pinterest.com\\\/aquamarinespa\\\/_created\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCvQ2S0WBOTcT7OEAVfISYHg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stainless steel hot tub Imaginox \u2248 Aquamarine Spa","description":"Choose the size, water filtration system, location, depth of the bathtub, but also the availability of individual massage points and nozzles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aquamarinespa.cz\/en\/products\/whirlpools\/stainless-steel-whirlpools-imaginox\/","og_locale":"en_US","og_type":"article","og_title":"Stainless steel hot tub Imaginox \u2248 Aquamarine Spa","og_description":"Choose the size, water filtration system, location, depth of the bathtub, but also the availability of individual massage points and nozzles.","og_url":"https:\/\/aquamarinespa.cz\/en\/products\/whirlpools\/stainless-steel-whirlpools-imaginox\/","og_site_name":"Aquamarine Spa","article_publisher":"https:\/\/www.facebook.com\/aquamarinespacz\/","article_modified_time":"2022-11-28T11:25:29+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aquamarinespa.cz\/en\/products\/whirlpools\/stainless-steel-whirlpools-imaginox\/","url":"https:\/\/aquamarinespa.cz\/en\/products\/whirlpools\/stainless-steel-whirlpools-imaginox\/","name":"Stainless steel hot tub Imaginox \u2248 Aquamarine Spa","isPartOf":{"@id":"https:\/\/aquamarinespa.cz\/en\/#website"},"datePublished":"2022-09-21T14:22:02+00:00","dateModified":"2022-11-28T11:25:29+00:00","description":"Choose the size, water filtration system, location, depth of the bathtub, but also the availability of individual massage points and nozzles.","breadcrumb":{"@id":"https:\/\/aquamarinespa.cz\/en\/products\/whirlpools\/stainless-steel-whirlpools-imaginox\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aquamarinespa.cz\/en\/products\/whirlpools\/stainless-steel-whirlpools-imaginox\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aquamarinespa.cz\/en\/products\/whirlpools\/stainless-steel-whirlpools-imaginox\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aquamarinespa.cz\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/aquamarinespa.cz\/en\/produkty\/"},{"@type":"ListItem","position":3,"name":"Whirlpools","item":"https:\/\/aquamarinespa.cz\/en\/produkty\/virivky\/"},{"@type":"ListItem","position":4,"name":"Stainless-steel whirlpools Imaginox"}]},{"@type":"WebSite","@id":"https:\/\/aquamarinespa.cz\/en\/#website","url":"https:\/\/aquamarinespa.cz\/en\/","name":"Aquamarine Spa","description":"Experience the feeling of perfection","publisher":{"@id":"https:\/\/aquamarinespa.cz\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aquamarinespa.cz\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/aquamarinespa.cz\/en\/#organization","name":"Aquamarine Spa","url":"https:\/\/aquamarinespa.cz\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aquamarinespa.cz\/en\/#\/schema\/logo\/image\/","url":"https:\/\/aquamarinespa.cz\/wp-content\/uploads\/2021\/10\/aquamarinespa-logo.jpg","contentUrl":"https:\/\/aquamarinespa.cz\/wp-content\/uploads\/2021\/10\/aquamarinespa-logo.jpg","width":1018,"height":499,"caption":"Aquamarine Spa"},"image":{"@id":"https:\/\/aquamarinespa.cz\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aquamarinespacz\/","https:\/\/www.instagram.com\/aquamarinespacz\/","https:\/\/cz.pinterest.com\/aquamarinespa\/_created\/","https:\/\/www.youtube.com\/channel\/UCvQ2S0WBOTcT7OEAVfISYHg"]}]}},"_links":{"self":[{"href":"https:\/\/aquamarinespa.cz\/en\/wp-json\/wp\/v2\/pages\/7349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aquamarinespa.cz\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aquamarinespa.cz\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aquamarinespa.cz\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aquamarinespa.cz\/en\/wp-json\/wp\/v2\/comments?post=7349"}],"version-history":[{"count":1,"href":"https:\/\/aquamarinespa.cz\/en\/wp-json\/wp\/v2\/pages\/7349\/revisions"}],"predecessor-version":[{"id":8034,"href":"https:\/\/aquamarinespa.cz\/en\/wp-json\/wp\/v2\/pages\/7349\/revisions\/8034"}],"up":[{"embeddable":true,"href":"https:\/\/aquamarinespa.cz\/en\/wp-json\/wp\/v2\/pages\/239"}],"wp:attachment":[{"href":"https:\/\/aquamarinespa.cz\/en\/wp-json\/wp\/v2\/media?parent=7349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}